{"id":42571,"date":"2024-03-27T16:21:17","date_gmt":"2024-03-27T15:21:17","guid":{"rendered":"https:\/\/www.port-adhoc.com\/?p=42571"},"modified":"2025-09-12T10:39:55","modified_gmt":"2025-09-12T08:39:55","slug":"le-port-de-bayonne-anglet-un-port-pour-la-navigation-maritime-et-fluviale","status":"publish","type":"post","link":"https:\/\/www.port-adhoc.com\/fr\/blog\/navigation-plaisance\/le-port-de-bayonne-anglet-un-port-pour-la-navigation-maritime-et-fluviale\/","title":{"rendered":"Le port de Bayonne Anglet, un port pour la navigation maritime et fluviale"},"content":{"rendered":"\n<p class=\"has-small-font-size\">Date de publication : 27\/03\/2024<\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><strong><strong><strong><strong><strong><strong><strong>Port Adhoc Bayonne Anglet : un port \u00e0 sec dans le Sud-Ouest<\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/h2>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Un point de d\u00e9part accessible facilement des plaisanciers<\/strong><\/h3>\n\n\n\n<p>Dans le Sud-ouest de la France, dans le d\u00e9partement des Pyr\u00e9n\u00e9es-Atlantiques, le <strong>Pays basque<\/strong> est une destination qui attire chaque ann\u00e9e de nombreux visiteurs. A terre ou en mer, ils sont heureux de venir d\u00e9couvrir la r\u00e9gion, souvent appr\u00e9ci\u00e9e pour sa proximit\u00e9 avec la <strong>nature<\/strong>, son <strong>architecture <\/strong>typique, son riche <strong>patrimoine culinaire<\/strong> et ses <strong>traditions<\/strong>. Les villes de Bayonne, Anglet et Biarritz, en particulier, sont des villes largement fr\u00e9quent\u00e9es.<\/p>\n\n\n\n<p>Au sein du r\u00e9seau de ports g\u00e9r\u00e9s par Port Adhoc, le <strong>port de plaisance de Bayonne Anglet<\/strong> est un point de d\u00e9part strat\u00e9gique pour explorer la r\u00e9gion. Au c\u0153ur du Pays basque et de la nature environnante, entre oc\u00e9an et rivi\u00e8re, mais aussi entre plage et for\u00eat, le <strong>port \u00e0 sec<\/strong> est <strong>ais\u00e9ment accessible<\/strong>. Par la route, il faut compter 50 minutes pour rejoindre le port de Bayonne Anglet depuis la ville de Dax, et 1h30 depuis Pau et Mont-de-Marsan. Depuis Irun, \u00e0 la fronti\u00e8re espagnole, 40 minutes suffisent \u00e0 rallier Port Adhoc Bayonne Anglet.<\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"575\" src=\"https:\/\/b2765252.smushcdn.com\/2765252\/wp-content\/uploads\/2024\/03\/Panorama-de-Bayonne-et-lAdour-1024x575.jpeg?lossy=1&strip=1&webp=1\" alt=\"\" class=\"wp-image-42576\" srcset=\"https:\/\/b2765252.smushcdn.com\/2765252\/wp-content\/uploads\/2024\/03\/Panorama-de-Bayonne-et-lAdour-1024x575.jpeg?lossy=1&strip=1&webp=1 1024w, https:\/\/b2765252.smushcdn.com\/2765252\/wp-content\/uploads\/2024\/03\/Panorama-de-Bayonne-et-lAdour-300x168.jpeg?lossy=1&strip=1&webp=1 300w, https:\/\/b2765252.smushcdn.com\/2765252\/wp-content\/uploads\/2024\/03\/Panorama-de-Bayonne-et-lAdour-768x431.jpeg?lossy=1&strip=1&webp=1 768w, https:\/\/b2765252.smushcdn.com\/2765252\/wp-content\/uploads\/2024\/03\/Panorama-de-Bayonne-et-lAdour-1536x862.jpeg?lossy=1&strip=1&webp=1 1536w, https:\/\/b2765252.smushcdn.com\/2765252\/wp-content\/uploads\/2024\/03\/Panorama-de-Bayonne-et-lAdour-2048x1149.jpeg?lossy=1&strip=1&webp=1 2048w, https:\/\/b2765252.smushcdn.com\/2765252\/wp-content\/uploads\/2024\/03\/Panorama-de-Bayonne-et-lAdour.jpeg?size=512x288&lossy=1&strip=1&webp=1 512w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Panorama de la ville de Bayonne et vue a\u00e9rienne sur l&rsquo;Adour<\/figcaption><\/figure>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>La c\u00f4te basque, une destination authentique<\/strong><\/h3>\n\n\n\n<p><strong>Bayonne<\/strong>, la capitale du Pays basque fran\u00e7ais, est d\u2019abord c\u00e9l\u00e8bre pour les traditionnelles <em>F\u00eates de Bayonne<\/em>. Mais il y a, sur place et quelle que soit la p\u00e9riode de l\u2019ann\u00e9e choisie pour visiter, bien d\u2019autres \u00e9l\u00e9ments \u00e0 appr\u00e9cier&nbsp;: la <strong>cath\u00e9drale Sainte-Marie de Bayonne<\/strong> \u2013 inscrite au patrimoine mondial de l\u2019UNESCO, le <strong>centre historique<\/strong> \u2013 avec les remparts et les ar\u00e8nes de la ville, le jardin botanique, le mus\u00e9e basque, l\u2019Atelier du chocolat\u2026<\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"681\" src=\"https:\/\/b2765252.smushcdn.com\/2765252\/wp-content\/uploads\/2024\/03\/Maisons-Bayonne-1024x681.jpeg?lossy=1&strip=1&webp=1\" alt=\"\" class=\"wp-image-42577\" srcset=\"https:\/\/b2765252.smushcdn.com\/2765252\/wp-content\/uploads\/2024\/03\/Maisons-Bayonne-1024x681.jpeg?lossy=1&strip=1&webp=1 1024w, https:\/\/b2765252.smushcdn.com\/2765252\/wp-content\/uploads\/2024\/03\/Maisons-Bayonne-300x200.jpeg?lossy=1&strip=1&webp=1 300w, https:\/\/b2765252.smushcdn.com\/2765252\/wp-content\/uploads\/2024\/03\/Maisons-Bayonne-768x511.jpeg?lossy=1&strip=1&webp=1 768w, https:\/\/b2765252.smushcdn.com\/2765252\/wp-content\/uploads\/2024\/03\/Maisons-Bayonne-1536x1022.jpeg?lossy=1&strip=1&webp=1 1536w, https:\/\/b2765252.smushcdn.com\/2765252\/wp-content\/uploads\/2024\/03\/Maisons-Bayonne-2048x1363.jpeg?lossy=1&strip=1&webp=1 2048w, https:\/\/b2765252.smushcdn.com\/2765252\/wp-content\/uploads\/2024\/03\/Maisons-Bayonne.jpeg?size=512x341&lossy=1&strip=1&webp=1 512w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" loading=\"lazy\" \/><figcaption class=\"wp-element-caption\">Les fa\u00e7ades traditionnelles de la ville de Bayonne, au coeur du Pays-Basque<\/figcaption><\/figure>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Il y a aussi beaucoup \u00e0 faire dans la ville voisine, <strong>Anglet<\/strong>. Celle-ci est r\u00e9put\u00e9e pour ses longues <strong>plages de sable<\/strong> \u2013 id\u00e9ales pour le farniente ou la pratique du <strong>surf<\/strong>, sa corniche et sa promenade. Vous le verrez, les <strong>for\u00eats de pins<\/strong> proches des plages apportent du charme aux paysages&nbsp;!&nbsp;Les amateurs de nature pourront compl\u00e9ter leur d\u00e9couverte du territoire avec la visite du <strong>Parc \u00e9cologique Izadia<\/strong>.<\/p>\n\n\n\n<p>A deux pas de Bayonne et d\u2019Anglet, un peu plus au sud, la ville de <strong>Biarritz<\/strong> offre, elle aussi, des sites et activit\u00e9s d\u2019int\u00e9r\u00eat. On visite la destination, une nouvelle fois, pour profiter des plages et pratiquer les sports nautiques. Mais, aussi, pour d\u00e9couvrir le <strong>Rocher de la Vierge<\/strong>, le centre-ville et ses halles ou le phare de la ville\u00a0!<\/p>\n\n\n\n<p>A terre ou en mer, vous l\u2019aurez compris, les villes, les paysages des Landes et le littoral ne manqueront pas de vous marquer. Ce n\u2019est pas pour rien que le Pays basque fait r\u00eaver\u2026<\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"649\" src=\"https:\/\/b2765252.smushcdn.com\/2765252\/wp-content\/uploads\/2024\/03\/Le-rocher-de-la-Cigale-a-Biarritz-1024x649.jpeg?lossy=1&strip=1&webp=1\" alt=\"\" class=\"wp-image-42578\" srcset=\"https:\/\/b2765252.smushcdn.com\/2765252\/wp-content\/uploads\/2024\/03\/Le-rocher-de-la-Cigale-a-Biarritz-1024x649.jpeg?lossy=1&strip=1&webp=1 1024w, https:\/\/b2765252.smushcdn.com\/2765252\/wp-content\/uploads\/2024\/03\/Le-rocher-de-la-Cigale-a-Biarritz-300x190.jpeg?lossy=1&strip=1&webp=1 300w, https:\/\/b2765252.smushcdn.com\/2765252\/wp-content\/uploads\/2024\/03\/Le-rocher-de-la-Cigale-a-Biarritz-768x487.jpeg?lossy=1&strip=1&webp=1 768w, https:\/\/b2765252.smushcdn.com\/2765252\/wp-content\/uploads\/2024\/03\/Le-rocher-de-la-Cigale-a-Biarritz-1536x974.jpeg?lossy=1&strip=1&webp=1 1536w, https:\/\/b2765252.smushcdn.com\/2765252\/wp-content\/uploads\/2024\/03\/Le-rocher-de-la-Cigale-a-Biarritz-2048x1299.jpeg?lossy=1&strip=1&webp=1 2048w, https:\/\/b2765252.smushcdn.com\/2765252\/wp-content\/uploads\/2024\/03\/Le-rocher-de-la-Cigale-a-Biarritz.jpeg?size=512x325&lossy=1&strip=1&webp=1 512w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" loading=\"lazy\" \/><figcaption class=\"wp-element-caption\">Le rocher de la Cigale \u00e0 Biarritz<\/figcaption><\/figure>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><strong><strong><strong><strong><strong><strong><strong>Un port de plaisance sur l&rsquo;Adour, entre mer et rivi\u00e8re<\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/h2>\n\n\n\n<p>Le port de plaisance de Bayonne Anglet est le point de d\u00e9part parfait pour <strong>visiter le Pays basque en bateau<\/strong>&nbsp;: tous les plaisanciers, qu\u2019ils souhaitent explorer la c\u00f4te basque atlantique ou d\u00e9couvrir les rives des rivi\u00e8res environnantes en navigation, appr\u00e9cieront sa localisation.<\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Des opportunit\u00e9s de navigation en zone maritime ou fluviale<\/strong><\/h3>\n\n\n\n<p>Le <strong>port \u00e0 sec de Bayonne Anglet<\/strong> est situ\u00e9 sur les bords de l\u2019Adour, dans la commune d\u2019Anglet et sur la rive gauche de la rivi\u00e8re. Pour le port de plaisance, il s\u2019agit d\u2019une localisation strat\u00e9gique permettant aux plaisanciers d\u2019envisager <strong>diff\u00e9rents programmes de navigation<\/strong> avec tous les types de navires&nbsp;:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Le port conviendra aux propri\u00e9taires qui souhaitent naviguer en <strong>zone fluviale<\/strong>, sur les rivi\u00e8res <strong>Adour<\/strong>, <strong>Bidouze<\/strong> et <strong>Gaves<\/strong>. Celles-ci sont navigables, en fonction du navire utilis\u00e9, sur pr\u00e8s de 150 kilom\u00e8tres. Les plaisanciers pourront admirer les paysages typiques du Pays basque et faire escale dans quelques ports comme Bayonne, Lahonce, Urt, Lanne, Guiche, Bidache ou Hastingues. Attention&nbsp;: il est essentiel de toujours prendre en consid\u00e9ration les profondeurs d\u2019eau, les mar\u00e9es et le tirant d\u2019air du bateau utilis\u00e9 pour naviguer sans encombre et s\u2019assurer de passer sous les diff\u00e9rents ponts&nbsp;!<\/li>\n<\/ul>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"427\" src=\"https:\/\/b2765252.smushcdn.com\/2765252\/wp-content\/uploads\/2024\/03\/Vue-aerienne-de-lAdour-a-Bayonne-1024x427.jpeg?lossy=1&strip=1&webp=1\" alt=\"\" class=\"wp-image-42574\" srcset=\"https:\/\/b2765252.smushcdn.com\/2765252\/wp-content\/uploads\/2024\/03\/Vue-aerienne-de-lAdour-a-Bayonne-1024x427.jpeg?lossy=1&strip=1&webp=1 1024w, https:\/\/b2765252.smushcdn.com\/2765252\/wp-content\/uploads\/2024\/03\/Vue-aerienne-de-lAdour-a-Bayonne-300x125.jpeg?lossy=1&strip=1&webp=1 300w, https:\/\/b2765252.smushcdn.com\/2765252\/wp-content\/uploads\/2024\/03\/Vue-aerienne-de-lAdour-a-Bayonne-768x321.jpeg?lossy=1&strip=1&webp=1 768w, https:\/\/b2765252.smushcdn.com\/2765252\/wp-content\/uploads\/2024\/03\/Vue-aerienne-de-lAdour-a-Bayonne-1536x641.jpeg?lossy=1&strip=1&webp=1 1536w, https:\/\/b2765252.smushcdn.com\/2765252\/wp-content\/uploads\/2024\/03\/Vue-aerienne-de-lAdour-a-Bayonne-2048x855.jpeg?lossy=1&strip=1&webp=1 2048w, https:\/\/b2765252.smushcdn.com\/2765252\/wp-content\/uploads\/2024\/03\/Vue-aerienne-de-lAdour-a-Bayonne.jpeg?size=512x214&lossy=1&strip=1&webp=1 512w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Vue a\u00e9rienne sur l&rsquo;Adour \u00e0 Bayonne<\/figcaption><\/figure>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<ul class=\"wp-block-list\">\n<li>A moins d\u2019un mille nautique de l\u2019oc\u00e9an Atlantique, Port Adhoc Bayonne Anglet sera aussi adapt\u00e9 \u00e0 tous ceux qui souhaitent naviguer en <strong>zone c\u00f4ti\u00e8re<\/strong>, <strong>en mer<\/strong>. Ils d\u00e9couvriront sans d\u00e9lai les beaut\u00e9s de la c\u00f4te basque fran\u00e7aise, et pourront \u00e9ventuellement prolonger leur croisi\u00e8re en ralliant le Pays basque espagnol.<\/li>\n<\/ul>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Le port de Bayonne, pour rejoindre le golfe de Gascogne<\/strong><\/h3>\n\n\n\n<p>Vous \u00eates plut\u00f4t adepte des navigations maritimes, mais en <strong>zone semi-hauturi\u00e8re<\/strong> ? Au-del\u00e0 des c\u00f4tes du Pays basque, vous pourrez aussi, depuis le port de Bayonne Anglet, rejoindre le <strong>Golfe de Gascogne<\/strong>. A vous les sessions de p\u00eache en navigation, en qu\u00eate d\u2019anchois, de merlu ou de sole&nbsp;!<\/p>\n\n\n\n<p>Si vous envisagez des navigations plus lointaines avec votre bateau \u00e0 moteur ou votre voilier, c\u2019est aussi le Golfe de Gascogne qui vous m\u00e8nera en Corogne, au Portugal, au sud de l\u2019Espagne ou, m\u00eame, \u00e0 Gibraltar.<\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><strong><strong><strong><strong><strong><strong><strong>Le port \u00e0 sec de Bayonne en d\u00e9tails<\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/h2>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Les infrastructures de Port Adhoc Bayonne Anglet<\/strong><\/h3>\n\n\n\n<p>Le port de plaisance de Bayonne Anglet est un port \u00e0 sec facilement accessible et parfaitement adapt\u00e9 \u00e0 l\u2019accueil des plaisanciers. Ouvert <strong>tous les jours de l\u2019ann\u00e9e<\/strong>, 7 jours sur 7, il a une capacit\u00e9 de <strong>210 emplacements de stockage sur racks<\/strong> et de <strong>30 emplacements sur bers<\/strong>. Le groupe Port Adhoc propose aussi aux propri\u00e9taires une <strong>aire de car\u00e9nage<\/strong>, une <strong>estacade de mise \u00e0 l\u2019eau<\/strong>, un lin\u00e9aire de <strong>80 m\u00e8tres de pontons priv\u00e9s<\/strong> ainsi qu\u2019un <strong>parking gratuit<\/strong>.<\/p>\n\n\n\n<p>Gr\u00e2ce au port de Bayonne Anglet et \u00e0 ses installations, les navigateurs peuvent profiter simplement et rapidement de belles navigations dans le Pays basque&nbsp;: le port de plaisance dispose d\u2019engins de levage permettant la <strong>sortie d\u2019eau<\/strong> ou la <strong>mise \u00e0 l\u2019eau<\/strong> des bateaux <strong>dans un<\/strong> <strong>laps de temps tr\u00e8s court<\/strong>, sur simple demande.<\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-buttons is-horizontal is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-fill\"><a class=\"wp-block-button__link has-white-color has-vivid-cyan-blue-background-color has-text-color has-background wp-element-button\" href=\"https:\/\/www.port-adhoc.com\/fr\/port-a-sec-bayonne-pays-basque\/\" target=\"_blank\" rel=\"noreferrer noopener\">D\u00e9couvrez notre port d&rsquo;Anglet \u27a1\ufe0f<\/a><\/div>\n<\/div>\n\n\n\n<div style=\"height:60px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Les autres services offerts aux plaisanciers<\/strong><\/h3>\n\n\n\n<p>Au-del\u00e0 des infrastructures portuaires qualitatives propos\u00e9es dans le port de Bayonne Anglet, les plaisanciers propri\u00e9taires b\u00e9n\u00e9ficient, sur place, d\u2019<strong>autres services<\/strong>. Parmi eux, une capitainerie avec terrasse, des sanitaires accessibles 24h\/24 tous les jours de l\u2019ann\u00e9e, ainsi que l\u2019acc\u00e8s au r\u00e9seau Wifi gratuit, sur l\u2019ensemble du port \u00e0 sec.<\/p>\n\n\n\n<p>Enfin, Port Adhoc Bayonne Anglet offre aussi l\u2019acc\u00e8s \u00e0 un large plateau technique de <strong>professionnels du nautisme<\/strong>&nbsp;: que les plaisanciers souhaitent b\u00e9n\u00e9ficier des services d\u2019un chantier naval, d\u2019un concessionnaire, d\u2019un sp\u00e9cialiste de l\u2019achat-vente de bateaux de plaisance et de p\u00eache ou de professionnels des loisirs nautiques, ils trouveront, dans l\u2019enceinte du port, les interlocuteurs dont ils ont besoin.<\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/b2765252.smushcdn.com\/2765252\/wp-content\/uploads\/2024\/03\/Dejeuner-plaisanciers-Port-Adhoc-Bayonne-Anglet-1024x683.jpg?lossy=1&strip=1&webp=1\" alt=\"\" class=\"wp-image-42581\" srcset=\"https:\/\/b2765252.smushcdn.com\/2765252\/wp-content\/uploads\/2024\/03\/Dejeuner-plaisanciers-Port-Adhoc-Bayonne-Anglet-1024x683.jpg?lossy=1&strip=1&webp=1 1024w, https:\/\/b2765252.smushcdn.com\/2765252\/wp-content\/uploads\/2024\/03\/Dejeuner-plaisanciers-Port-Adhoc-Bayonne-Anglet-300x200.jpg?lossy=1&strip=1&webp=1 300w, https:\/\/b2765252.smushcdn.com\/2765252\/wp-content\/uploads\/2024\/03\/Dejeuner-plaisanciers-Port-Adhoc-Bayonne-Anglet-768x512.jpg?lossy=1&strip=1&webp=1 768w, https:\/\/b2765252.smushcdn.com\/2765252\/wp-content\/uploads\/2024\/03\/Dejeuner-plaisanciers-Port-Adhoc-Bayonne-Anglet-1536x1024.jpg?lossy=1&strip=1&webp=1 1536w, https:\/\/b2765252.smushcdn.com\/2765252\/wp-content\/uploads\/2024\/03\/Dejeuner-plaisanciers-Port-Adhoc-Bayonne-Anglet-2048x1365.jpg?lossy=1&strip=1&webp=1 2048w, https:\/\/b2765252.smushcdn.com\/2765252\/wp-content\/uploads\/2024\/03\/Dejeuner-plaisanciers-Port-Adhoc-Bayonne-Anglet.jpg?size=512x342&lossy=1&strip=1&webp=1 512w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">D\u00e9jeuner estival des plaisanciers \u00e0 Port Adhoc Bayonne Anglet<\/figcaption><\/figure>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Obtenir une place au port d&rsquo;Anglet<\/strong><\/h3>\n\n\n\n<p>Vous aussi, vous souhaitez <strong>placer votre bateau au port de Bayonne Anglet<\/strong>, pour profiter de <strong>navigations dans le Pays basque<\/strong> toute l\u2019ann\u00e9e&nbsp;? Contactez-nous ! L\u2019\u00e9quipe Port Adhoc&nbsp;se fera un plaisir de vous assister dans la r\u00e9alisation de votre projet.<\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-buttons is-horizontal is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-fill\"><a class=\"wp-block-button__link has-white-color has-vivid-cyan-blue-background-color has-text-color has-background has-small-font-size has-custom-font-size wp-element-button\" href=\"https:\/\/www.port-adhoc.com\/fr\/obtenir-un-devis\/\" target=\"_blank\" rel=\"noreferrer noopener\">Nous contacter \ud83d\udc4b<\/a><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Dans le Pays basque, le port de plaisance de Bayonne Anglet permet le stockage de bateaux \u00e0 sec toute l\u2019ann\u00e9e, entre mer et for\u00eat. Depuis Port Adhoc Bayonne Anglet, les plaisanciers peuvent profiter \u00e0 la fois de navigations maritimes, sur la c\u00f4te basque et dans le golfe de Gascogne, et de navigations fluviales, sur l\u2019Adour, la Bidouze et le Gaves. Si vous \u00eates int\u00e9ress\u00e9 par l\u2019id\u00e9e de naviguer dans la r\u00e9gion, l\u2019\u00e9quipe de Port Adhoc vous en dit plus dans cet article.<\/p>\n","protected":false},"author":2,"featured_media":115396,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"wds_primary_category":42,"footnotes":""},"categories":[42],"tags":[49],"class_list":["post-42571","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-navigation-plaisance","tag-port-adhoc-bayonne-anglet"],"_links":{"self":[{"href":"https:\/\/www.port-adhoc.com\/fr\/wp-json\/wp\/v2\/posts\/42571","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.port-adhoc.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.port-adhoc.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.port-adhoc.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.port-adhoc.com\/fr\/wp-json\/wp\/v2\/comments?post=42571"}],"version-history":[{"count":0,"href":"https:\/\/www.port-adhoc.com\/fr\/wp-json\/wp\/v2\/posts\/42571\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.port-adhoc.com\/fr\/wp-json\/wp\/v2\/media\/115396"}],"wp:attachment":[{"href":"https:\/\/www.port-adhoc.com\/fr\/wp-json\/wp\/v2\/media?parent=42571"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.port-adhoc.com\/fr\/wp-json\/wp\/v2\/categories?post=42571"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.port-adhoc.com\/fr\/wp-json\/wp\/v2\/tags?post=42571"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}